{"id":81825,"date":"2025-06-05T09:53:47","date_gmt":"2025-06-05T07:53:47","guid":{"rendered":"https:\/\/magnetarmagnets.com\/?post_type=product&#038;p=81825"},"modified":"2025-09-13T22:38:00","modified_gmt":"2025-09-13T20:38:00","slug":"pacchetto-magnete-da-pesca-per-bambini-110-kg-monofacciale","status":"publish","type":"product","link":"https:\/\/test.magnetarmagnets.com\/it\/shop\/pacchetto-magnete-da-pesca-per-bambini-110-kg-monofacciale\/","title":{"rendered":"Pacchetto magnete da pesca per bambini &#8211; 110 kg &#8211; monofacciale"},"content":{"rendered":"<p>Il tuo bambino desidera iniziare la pesca con magnete? Questo pacchetto per bambini \u00e8 perfetto per loro. Il nostro Kids Package contiene un magnete adatto ai bambini fino a 10 anni. Il divertimento non finisce mai con il nostro <a href=\"https:\/\/test.magnetarmagnets.com\/shop\/classic-fishing-magnet-240lb-110kg\/\"><strong>Classic Fishing Magnet 240 lb \/ 110 kg<\/strong><\/a>. Questo magnete \u00e8 dotato di alloggiamento in acciaio protettivo, rendendolo un magnete pratico per i pi\u00f9 piccoli. Il peso ideale consente alla maggior parte dei bambini dai 6 anni in su di lanciarlo facilmente. Con lo sconto pacchetto, la fune e la colla metallica incluse sono particolarmente convenienti.<\/p>\n<h2>Kids Package 240 lb \/ 110 kg &#8211; contenuto monofacciale<\/h2>\n<p>Il Classic Fishing Magnet 240 lb \/ 110 kg \u00e8 un\u2019opzione economica per iniziare la pesca con magnete. Il magnete monofacciale esercita la forza magnetica solo dal lato inferiore. Poich\u00e9 tutta la forza \u00e8 concentrata in una direzione, questo magnete pu\u00f2 risultare piuttosto potente se le circostanze sono quelle giuste.<\/p>\n<p>La forza magnetica di 240 lb \/ 110 kg si ottiene solo in condizioni perfette, cio\u00e8 quando il magnete tocca una piastra di metallo non ossidata di 2 cm di spessore. La probabilit\u00e0 che ci\u00f2 avvenga durante la pesca con magnete, di solito, non \u00e8 molto alta. Vuoi sapere come si determina la forza di trazione di un magnete da pesca? Guarda il nostro video sul <a href=\"https:\/\/www.youtube.com\/watch?v=2McW3RURDxs&amp;t=14s\"><strong>test di forza magnetica<\/strong><\/a> che utilizziamo.<\/p>\n<p>Nella maggior parte dei casi, il Classic Fishing Magnet 240 lb \/ 110 kg non \u00e8 potente come molti dei nostri altri modelli. Ecco perch\u00e9 questo magnete \u00e8 perfetto per i bambini che pescano oggetti pi\u00f9 piccoli come chiavi e monete. Hai degli adolescenti e cerchi un magnete leggermente pi\u00f9 forte? Considera il nostro <a href=\"https:\/\/test.magnetarmagnets.com\/shop\/starterpackage\/\"><strong>Starter Package<\/strong><\/a>!<\/p>\n<h2>Alta qualit\u00e0<\/h2>\n<p>Tutti i magneti da pesca Magnetar sono realizzati in neodimio. Questo materiale garantisce una forza magnetica duratura. Se usati e conservati correttamente, questi magneti perdono solo l\u20191% della loro forza in 100 anni. Per questo siamo certi di offrire i magneti da pesca di massima qualit\u00e0 sul mercato.<\/p>\n<p>Negli ultimi anni, il mercato \u00e8 stato invaso da prodotti di bassa qualit\u00e0. Molti magneti da pesca di altri venditori perdono la loro forza in poche settimane. Generalmente si tratta di magneti di dimensioni maggiori, ma realizzati con neodimio di qualit\u00e0 inferiore e pubblicizzati con annunci ingannevoli. Questi prodotti possono sembrare economici, ma a lungo termine lasceranno l\u2019utente insoddisfatto.<\/p>\n<p>Magnetar \u00e8 una piccola azienda a conduzione familiare formata da veri appassionati di pesca con magnete. La qualit\u00e0 viene prima di tutto, e questo si riflette nei nostri prodotti. Tutti i nostri magneti da pesca sono progettati internamente per garantire prodotti di alto livello. Cerchi un magnete da pesca affidabile, efficace e di qualit\u00e0? Scegli un Magnetar!<\/p>\n<h2>Avvertenza:<\/h2>\n<p>I nostri magneti da pesca in neodimio sono molto potenti. Ci\u00f2 pu\u00f2 causare il richiamo di altri oggetti verso il magnete ad alta velocit\u00e0. Ovviamente, questo comporta situazioni potenzialmente pericolose, poich\u00e9 le dita potrebbero rimanere intrappolate tra magnete e oggetto. Raccomandiamo di maneggiare sempre questi magneti con cura e sottolineiamo che lo si fa a proprio rischio. Leggi le nostre avvertenze di sicurezza prima dell\u2019uso.<\/p>\n<p>Non dimenticare di visitare i nostri <a href=\"https:\/\/test.magnetarmagnets.com\/\" target=\"_blank\" rel=\"noopener\">magneti da pesca in vendita<\/a> e i nostri <a href=\"https:\/\/test.magnetarmagnets.com\/collections\/fishing-magnets\/magnet-fishing-kit\/\" target=\"_blank\" rel=\"noopener\">kit per pesca con magnete<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pesca con magnete per <strong>bambini<\/strong>? \u00c8 possibile con il <strong>set per bambini da 110 kg<\/strong>. Con un <strong>magnete da pesca monofacciale, una fune e colla per fissaggio<\/strong>, i bambini dai sei anni possono iniziare sotto l&#8217;attento sguardo dei genitori.<\/p>\n","protected":false},"featured_media":72569,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"product_brand":[],"product_cat":[480,473,479,482,1005],"product_tag":[],"class_list":{"0":"post-81825","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-kit-per-la-pesca-magnetica","7":"product_cat-magneti-da-pesca","8":"product_cat-magneti-da-pesca-a-faccia-singola","9":"product_cat-per-principianti-e-bambini","10":"product_cat-tutti-i-prodotti","12":"first","13":"instock","14":"sale","15":"taxable","16":"shipping-taxable","17":"purchasable","18":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pacchetto magnete da pesca per bambini - 110 kg - monofacciale - Magnet fishing with a Magnetar fishing magnet<\/title>\n<meta name=\"description\" content=\"Pacchetto magnete da pesca per bambini - 110 kg monofacciale - Magnetar\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/test.magnetarmagnets.com\/it\/shop\/pacchetto-magnete-da-pesca-per-bambini-110-kg-monofacciale\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pacchetto magnete da pesca per bambini - 110 kg - monofacciale - Magnet fishing with a Magnetar fishing magnet\" \/>\n<meta property=\"og:description\" content=\"Pacchetto magnete da pesca per bambini - 110 kg monofacciale - Magnetar\" \/>\n<meta property=\"og:url\" content=\"https:\/\/test.magnetarmagnets.com\/it\/shop\/pacchetto-magnete-da-pesca-per-bambini-110-kg-monofacciale\/\" \/>\n<meta property=\"og:site_name\" content=\"Magnet fishing with a Magnetar fishing magnet\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/fishingmagnets\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-13T20:38:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/test.magnetarmagnets.com\/wp-content\/uploads\/2021\/10\/MAGNETAR-KINDER-SET-GOOGLE.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"1500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"WebPage\",\"ItemPage\"],\"@id\":\"https:\\\/\\\/test.magnetarmagnets.com\\\/it\\\/shop\\\/pacchetto-magnete-da-pesca-per-bambini-110-kg-monofacciale\\\/\",\"url\":\"https:\\\/\\\/test.magnetarmagnets.com\\\/it\\\/shop\\\/pacchetto-magnete-da-pesca-per-bambini-110-kg-monofacciale\\\/\",\"name\":\"Pacchetto magnete da pesca per bambini - 110 kg - monofacciale - Magnet fishing with a Magnetar fishing magnet\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/test.magnetarmagnets.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/test.magnetarmagnets.com\\\/it\\\/shop\\\/pacchetto-magnete-da-pesca-per-bambini-110-kg-monofacciale\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/test.magnetarmagnets.com\\\/it\\\/shop\\\/pacchetto-magnete-da-pesca-per-bambini-110-kg-monofacciale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/test.magnetarmagnets.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/MAGNETAR-KINDER-SET-GOOGLE.jpg\",\"datePublished\":\"2025-06-05T07:53:47+00:00\",\"dateModified\":\"2025-09-13T20:38:00+00:00\",\"description\":\"Pacchetto magnete da pesca per bambini - 110 kg monofacciale - Magnetar\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/test.magnetarmagnets.com\\\/it\\\/shop\\\/pacchetto-magnete-da-pesca-per-bambini-110-kg-monofacciale\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/test.magnetarmagnets.com\\\/it\\\/shop\\\/pacchetto-magnete-da-pesca-per-bambini-110-kg-monofacciale\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/test.magnetarmagnets.com\\\/it\\\/shop\\\/pacchetto-magnete-da-pesca-per-bambini-110-kg-monofacciale\\\/#primaryimage\",\"url\":\"https:\\\/\\\/test.magnetarmagnets.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/MAGNETAR-KINDER-SET-GOOGLE.jpg\",\"contentUrl\":\"https:\\\/\\\/test.magnetarmagnets.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/MAGNETAR-KINDER-SET-GOOGLE.jpg\",\"width\":1500,\"height\":1500,\"caption\":\"MAGNETAR-KINDER-SET\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/test.magnetarmagnets.com\\\/it\\\/shop\\\/pacchetto-magnete-da-pesca-per-bambini-110-kg-monofacciale\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/test.magnetarmagnets.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"negozio\",\"item\":\"https:\\\/\\\/test.magnetarmagnets.com\\\/it\\\/negozio\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Magneti da Pesca\",\"item\":\"https:\\\/\\\/test.magnetarmagnets.com\\\/it\\\/collections\\\/magneti-da-pesca\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Magneti da Pesca a Faccia Singola\",\"item\":\"https:\\\/\\\/test.magnetarmagnets.com\\\/it\\\/collections\\\/magneti-da-pesca\\\/magneti-da-pesca-a-faccia-singola\\\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"Pacchetto magnete da pesca per bambini &#8211; 110 kg &#8211; monofacciale\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/test.magnetarmagnets.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/test.magnetarmagnets.com\\\/it\\\/\",\"name\":\"Magnet fishing with a Magnetar fishing magnet\",\"description\":\"Powerful magnets for magnet fishing\",\"publisher\":{\"@id\":\"https:\\\/\\\/test.magnetarmagnets.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/test.magnetarmagnets.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/test.magnetarmagnets.com\\\/it\\\/#organization\",\"name\":\"Magnetar\",\"url\":\"https:\\\/\\\/test.magnetarmagnets.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/test.magnetarmagnets.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/magnetarmagnets.com\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/magnetarvismagneet_logo.png\",\"contentUrl\":\"https:\\\/\\\/magnetarmagnets.com\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/magnetarvismagneet_logo.png\",\"width\":209,\"height\":100,\"caption\":\"Magnetar\"},\"image\":{\"@id\":\"https:\\\/\\\/test.magnetarmagnets.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/fishingmagnets\\\/\",\"https:\\\/\\\/www.instagram.com\\\/magnetar_magnets\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/magnetarbv\\\/?originalSubdomain=nl\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/MagnetarVismagneet\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pacchetto magnete da pesca per bambini - 110 kg - monofacciale - Magnet fishing with a Magnetar fishing magnet","description":"Pacchetto magnete da pesca per bambini - 110 kg monofacciale - Magnetar","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/test.magnetarmagnets.com\/it\/shop\/pacchetto-magnete-da-pesca-per-bambini-110-kg-monofacciale\/","og_locale":"it_IT","og_type":"article","og_title":"Pacchetto magnete da pesca per bambini - 110 kg - monofacciale - Magnet fishing with a Magnetar fishing magnet","og_description":"Pacchetto magnete da pesca per bambini - 110 kg monofacciale - Magnetar","og_url":"https:\/\/test.magnetarmagnets.com\/it\/shop\/pacchetto-magnete-da-pesca-per-bambini-110-kg-monofacciale\/","og_site_name":"Magnet fishing with a Magnetar fishing magnet","article_publisher":"https:\/\/www.facebook.com\/fishingmagnets\/","article_modified_time":"2025-09-13T20:38:00+00:00","og_image":[{"width":1500,"height":1500,"url":"https:\/\/test.magnetarmagnets.com\/wp-content\/uploads\/2021\/10\/MAGNETAR-KINDER-SET-GOOGLE.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["WebPage","ItemPage"],"@id":"https:\/\/test.magnetarmagnets.com\/it\/shop\/pacchetto-magnete-da-pesca-per-bambini-110-kg-monofacciale\/","url":"https:\/\/test.magnetarmagnets.com\/it\/shop\/pacchetto-magnete-da-pesca-per-bambini-110-kg-monofacciale\/","name":"Pacchetto magnete da pesca per bambini - 110 kg - monofacciale - Magnet fishing with a Magnetar fishing magnet","isPartOf":{"@id":"https:\/\/test.magnetarmagnets.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/test.magnetarmagnets.com\/it\/shop\/pacchetto-magnete-da-pesca-per-bambini-110-kg-monofacciale\/#primaryimage"},"image":{"@id":"https:\/\/test.magnetarmagnets.com\/it\/shop\/pacchetto-magnete-da-pesca-per-bambini-110-kg-monofacciale\/#primaryimage"},"thumbnailUrl":"https:\/\/test.magnetarmagnets.com\/wp-content\/uploads\/2021\/10\/MAGNETAR-KINDER-SET-GOOGLE.jpg","datePublished":"2025-06-05T07:53:47+00:00","dateModified":"2025-09-13T20:38:00+00:00","description":"Pacchetto magnete da pesca per bambini - 110 kg monofacciale - Magnetar","breadcrumb":{"@id":"https:\/\/test.magnetarmagnets.com\/it\/shop\/pacchetto-magnete-da-pesca-per-bambini-110-kg-monofacciale\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/test.magnetarmagnets.com\/it\/shop\/pacchetto-magnete-da-pesca-per-bambini-110-kg-monofacciale\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/test.magnetarmagnets.com\/it\/shop\/pacchetto-magnete-da-pesca-per-bambini-110-kg-monofacciale\/#primaryimage","url":"https:\/\/test.magnetarmagnets.com\/wp-content\/uploads\/2021\/10\/MAGNETAR-KINDER-SET-GOOGLE.jpg","contentUrl":"https:\/\/test.magnetarmagnets.com\/wp-content\/uploads\/2021\/10\/MAGNETAR-KINDER-SET-GOOGLE.jpg","width":1500,"height":1500,"caption":"MAGNETAR-KINDER-SET"},{"@type":"BreadcrumbList","@id":"https:\/\/test.magnetarmagnets.com\/it\/shop\/pacchetto-magnete-da-pesca-per-bambini-110-kg-monofacciale\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/test.magnetarmagnets.com\/it\/"},{"@type":"ListItem","position":2,"name":"negozio","item":"https:\/\/test.magnetarmagnets.com\/it\/negozio\/"},{"@type":"ListItem","position":3,"name":"Magneti da Pesca","item":"https:\/\/test.magnetarmagnets.com\/it\/collections\/magneti-da-pesca\/"},{"@type":"ListItem","position":4,"name":"Magneti da Pesca a Faccia Singola","item":"https:\/\/test.magnetarmagnets.com\/it\/collections\/magneti-da-pesca\/magneti-da-pesca-a-faccia-singola\/"},{"@type":"ListItem","position":5,"name":"Pacchetto magnete da pesca per bambini &#8211; 110 kg &#8211; monofacciale"}]},{"@type":"WebSite","@id":"https:\/\/test.magnetarmagnets.com\/it\/#website","url":"https:\/\/test.magnetarmagnets.com\/it\/","name":"Magnet fishing with a Magnetar fishing magnet","description":"Powerful magnets for magnet fishing","publisher":{"@id":"https:\/\/test.magnetarmagnets.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/test.magnetarmagnets.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/test.magnetarmagnets.com\/it\/#organization","name":"Magnetar","url":"https:\/\/test.magnetarmagnets.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/test.magnetarmagnets.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/magnetarmagnets.com\/wp-content\/uploads\/2021\/01\/magnetarvismagneet_logo.png","contentUrl":"https:\/\/magnetarmagnets.com\/wp-content\/uploads\/2021\/01\/magnetarvismagneet_logo.png","width":209,"height":100,"caption":"Magnetar"},"image":{"@id":"https:\/\/test.magnetarmagnets.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/fishingmagnets\/","https:\/\/www.instagram.com\/magnetar_magnets\/","https:\/\/www.linkedin.com\/company\/magnetarbv\/?originalSubdomain=nl","https:\/\/www.youtube.com\/c\/MagnetarVismagneet"]}]}},"_links":{"self":[{"href":"https:\/\/test.magnetarmagnets.com\/it\/wp-json\/wp\/v2\/product\/81825","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/test.magnetarmagnets.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/test.magnetarmagnets.com\/it\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/test.magnetarmagnets.com\/it\/wp-json\/wp\/v2\/comments?post=81825"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/test.magnetarmagnets.com\/it\/wp-json\/wp\/v2\/media\/72569"}],"wp:attachment":[{"href":"https:\/\/test.magnetarmagnets.com\/it\/wp-json\/wp\/v2\/media?parent=81825"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/test.magnetarmagnets.com\/it\/wp-json\/wp\/v2\/product_brand?post=81825"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/test.magnetarmagnets.com\/it\/wp-json\/wp\/v2\/product_cat?post=81825"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/test.magnetarmagnets.com\/it\/wp-json\/wp\/v2\/product_tag?post=81825"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}